{"id":67468,"date":"2023-04-29T11:09:55","date_gmt":"2023-04-29T14:09:55","guid":{"rendered":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/?p=67468"},"modified":"2023-04-29T11:09:55","modified_gmt":"2023-04-29T14:09:55","slug":"inauguraron-la-nueva-central-de-emergencias-para-ambulancias","status":"publish","type":"post","link":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/","title":{"rendered":"Inauguraron la nueva Central de Emergencias para ambulancias"},"content":{"rendered":"<p><strong>La nueva central est\u00e1 ubicada en Carlos Casares y Entre R\u00edos, en el mismo predio donde funciona el Centro de Salud 31.\u00a0<\/strong><\/p><div id=\"sanfe-34578140\" class=\"sanfe-contenido sanfe-entity-placement\" style=\"margin-top: 1px;margin-right: 2px;\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- anuncio -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-6719099566820218\"\r\n     data-ad-slot=\"4258158415\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p>El Municipio de San Fernando inaugur\u00f3 la nueva Central de Emergencias que est\u00e1 ubicada en Carlos Casares y Entre R\u00edos, detr\u00e1s del nuevo Centro de Salud 31 y en cercan\u00edas de los barrios Mil Viviendas y Santa Rosa.<\/p>\n<p><a href=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/35.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-67472 size-medium\" src=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/35-300x225.jpg\" alt=\"3\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/35-300x225.jpg 300w, https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/35-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El intendente, Juan Andreotti, encabez\u00f3 la inauguraci\u00f3n y destac\u00f3: \u201cEsta nueva Central de Emergencias est\u00e1 ubicada en una zona estrat\u00e9gica de la ciudad, lo que nos permite mejorar la cobertura brindando un mejor servicio. Adem\u00e1s, hace unos meses incorporamos un nuevo equipo de profesionales y coordinadora, pudiendo ofrecer una mejora de los niveles de respuesta y un servicio de calidad\u201d.<\/p>\n<p>\u201cEsta inversi\u00f3n que hacemos en conjunto mejora todo el sistema sanitario: venimos invirtiendo en nuestro Hospital Municipal San Cayetano, aumentando el nivel de las prestaciones que brindamos; tambi\u00e9n haciendo obras de renovaci\u00f3n del Hospital Provincial Petrona de Cordero, porque es muy importante cuidarnos entre todos, apuntando a tener un sistema de salud de calidad para mejorar el nivel de vida de las vecinas y vecinos de San Fernando\u201d, concluy\u00f3 Andreotti.<\/p>\n<p><a href=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/45.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-67470 size-medium\" src=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/45-300x225.jpg\" alt=\"Central de Emergencias\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/45-300x225.jpg 300w, https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/45-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En tanto, el secretario de Salud, Marcelo Campos, agreg\u00f3: \u201cLa gente puede comunicarse por celular al n\u00famero 107, o por la l\u00ednea gratuita 0800-888-3633 las 24 horas los 365 d\u00edas del a\u00f1o. Tambi\u00e9n estamos incorporando el tel\u00e9fono conjuntamente con el servicio que prestamos en Islas; nuestra base de datos \u00fanica funciona desde que recibimos el llamado, con la recepci\u00f3n del paciente que es trasladado en lancha al continente, donde lo espera una ambulancia para su traslado a cualquier hospital o Centro de Salud. Esto permite un servicio de mayor calidad y de pronta respuesta\u201d.<\/p>\n<p>\u201cEste es un espacio mucho m\u00e1s c\u00f3modo, con instalaciones para hombres y mujeres, con amplia cobertura de Historia Cl\u00ednica Digital y sistema de comunicaci\u00f3n. Cuando la vecina o vecino realiza un llamado, se recibe en el Centro de Operaciones, donde adem\u00e1s del servicio de ambulancia tambi\u00e9n est\u00e1n el Servicio de Prevenci\u00f3n Comunitaria, el monitoreo de las C\u00e1maras de Seguridad, desde donde se deriva la informaci\u00f3n a esta Base de Operaciones que despacha la ambulancia desde aqu\u00ed, desde una Posta, o la que est\u00e9 m\u00e1s cercana al lugar en base a 4 c\u00f3digos: rojo (riesgo de vida), amarillo (emergencia), verde, y azul (traslados)\u201d.<\/p>\n<p>En la inauguraci\u00f3n, estuvieron presentes adem\u00e1s la subsecretaria de Salud, Claudia Regenjo; la secretaria de Obras P\u00fablicas, Cecilia Tucat; m\u00e1s funcionarios y concejales, y el personal de Emergencias San Fernando.<\/p>\n<p>[embedyt] https:\/\/www.youtube.com\/watch?v=gIyxz1I4sQw[\/embedyt]<\/p>\n<p>Fuente: San Fernando Municipio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva central est\u00e1 ubicada en Carlos Casares y Entre R\u00edos, en el mismo predio donde funciona el Centro de Salud 31.\u00a0 El Municipio de San Fernando inaugur\u00f3 la nueva<\/p>\n","protected":false},"author":3,"featured_media":67469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[1810,5597],"class_list":["post-67468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general","tag-ambulancia","tag-central-de-emergencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro\" \/>\n<meta property=\"og:description\" content=\"La nueva central est\u00e1 ubicada en Carlos Casares y Entre R\u00edos, en el mismo predio donde funciona el Centro de Salud 31.\u00a0 El Municipio de San Fernando inaugur\u00f3 la nueva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/\" \/>\n<meta property=\"og:site_name\" content=\"San Fernando Nuestro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SanFernandoNuestro\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sabrina.v.garcia\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T14:09:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4176\" \/>\n\t<meta property=\"og:image:height\" content=\"2784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabrina Garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/garciasabri?lang=es\" \/>\n<meta name=\"twitter:site\" content=\"@sfnuestro\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/\"},\"author\":{\"name\":\"Sabrina Garcia\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b42a4d7cb7767aa65f3c9bb2861fcbe7\"},\"headline\":\"Inauguraron la nueva Central de Emergencias para ambulancias\",\"datePublished\":\"2023-04-29T14:09:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/29.jpg\",\"keywords\":[\"ambulancia\",\"Central de Emergencias\"],\"articleSection\":[\"INFORMACI\u00d3N GENERAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/\",\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/\",\"name\":\"Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/29.jpg\",\"datePublished\":\"2023-04-29T14:09:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/29.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/29.jpg\",\"width\":4176,\"height\":2784},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguraron la nueva Central de Emergencias para ambulancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/\",\"name\":\"San Fernando Nuestro\",\"description\":\"Un Lugar de Encuentro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#organization\",\"name\":\"San Fernando Nuestro\",\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sfn-marca.png\",\"contentUrl\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/sfn-marca.png\",\"width\":390,\"height\":116,\"caption\":\"San Fernando Nuestro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SanFernandoNuestro\\\/\",\"https:\\\/\\\/x.com\\\/sfnuestro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b42a4d7cb7767aa65f3c9bb2861fcbe7\",\"name\":\"Sabrina Garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g\",\"caption\":\"Sabrina Garcia\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sabrina.v.garcia\",\"sgarcia\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/garciasabri?lang=es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/garciasabri\"],\"url\":\"https:\\\/\\\/www.sanfernandonuestro.com.ar\\\/wp\\\/author\\\/sgarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/","og_locale":"es_ES","og_type":"article","og_title":"Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro","og_description":"La nueva central est\u00e1 ubicada en Carlos Casares y Entre R\u00edos, en el mismo predio donde funciona el Centro de Salud 31.\u00a0 El Municipio de San Fernando inaugur\u00f3 la nueva","og_url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/","og_site_name":"San Fernando Nuestro","article_publisher":"https:\/\/www.facebook.com\/SanFernandoNuestro\/","article_author":"https:\/\/www.facebook.com\/sabrina.v.garcia","article_published_time":"2023-04-29T14:09:55+00:00","og_image":[{"width":4176,"height":2784,"url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg","type":"image\/jpeg"}],"author":"Sabrina Garcia","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/garciasabri?lang=es","twitter_site":"@sfnuestro","twitter_misc":{"Escrito por":"Sabrina Garcia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#article","isPartOf":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/"},"author":{"name":"Sabrina Garcia","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#\/schema\/person\/b42a4d7cb7767aa65f3c9bb2861fcbe7"},"headline":"Inauguraron la nueva Central de Emergencias para ambulancias","datePublished":"2023-04-29T14:09:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#organization"},"image":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg","keywords":["ambulancia","Central de Emergencias"],"articleSection":["INFORMACI\u00d3N GENERAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/","url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/","name":"Inauguraron la nueva Central de Emergencias para ambulancias - San Fernando Nuestro","isPartOf":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#primaryimage"},"image":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg","datePublished":"2023-04-29T14:09:55+00:00","breadcrumb":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#primaryimage","url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg","contentUrl":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2023\/04\/29.jpg","width":4176,"height":2784},{"@type":"BreadcrumbList","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/inauguraron-la-nueva-central-de-emergencias-para-ambulancias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/"},{"@type":"ListItem","position":2,"name":"Inauguraron la nueva Central de Emergencias para ambulancias"}]},{"@type":"WebSite","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#website","url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/","name":"San Fernando Nuestro","description":"Un Lugar de Encuentro","publisher":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#organization","name":"San Fernando Nuestro","url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2026\/07\/sfn-marca.png","contentUrl":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-content\/uploads\/2026\/07\/sfn-marca.png","width":390,"height":116,"caption":"San Fernando Nuestro"},"image":{"@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SanFernandoNuestro\/","https:\/\/x.com\/sfnuestro"]},{"@type":"Person","@id":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/#\/schema\/person\/b42a4d7cb7767aa65f3c9bb2861fcbe7","name":"Sabrina Garcia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/635861e691b92a500308c1d7346bf695f797b11664daf3c231692c62a64f23fb?s=96&d=mm&r=g","caption":"Sabrina Garcia"},"sameAs":["https:\/\/www.facebook.com\/sabrina.v.garcia","sgarcia","https:\/\/x.com\/https:\/\/twitter.com\/garciasabri?lang=es","https:\/\/www.youtube.com\/user\/garciasabri"],"url":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/author\/sgarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/posts\/67468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/comments?post=67468"}],"version-history":[{"count":2,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/posts\/67468\/revisions"}],"predecessor-version":[{"id":67482,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/posts\/67468\/revisions\/67482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/media\/67469"}],"wp:attachment":[{"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/media?parent=67468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/categories?post=67468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sanfernandonuestro.com.ar\/wp\/wp-json\/wp\/v2\/tags?post=67468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}